{"id":13893,"date":"2022-01-31T14:23:36","date_gmt":"2022-01-31T17:23:36","guid":{"rendered":"https:\/\/www.buenosairesfreewalks.com\/spanish\/?p=13893"},"modified":"2022-01-31T14:49:39","modified_gmt":"2022-01-31T17:49:39","slug":"tour-diego-armando-maradona","status":"publish","type":"post","link":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/","title":{"rendered":"Tour Diego Armando Maradona"},"content":{"rendered":"<p><strong>Tour Diego Armando Maradona<\/strong>, un recorrido por los barrios que homenajean al \u00eddolo nacional, reconocido por el mundo entero!<\/p>\n<p>Hace un a\u00f1o que <strong>El Diego, o D10S<\/strong>, como se lo conoce popularmente, abandon\u00f3 la vida terrenal, para sorpresa del mundo. S\u00ed, es <strong>una de las personalidades m\u00e1s fuertes y el mayor \u00eddolo que poseen los argentinos.<\/strong> Su partida gener\u00f3 mucha tristeza para todos, y siempre habr\u00e1 motivos para homenajearlo y recordarlo.<!--more--><\/p>\n<p>Por eso mismo, aqu\u00ed queremos darte a conocer un tour por<strong> aquellos lugares que fueron historia en su propia vida.<\/strong> Adem\u00e1s de <strong>conocer los sitios m\u00e1s importantes para el Diego, vas a poder visitar diferentes barrios y seguir conociendo m\u00e1s de la ciudad de Buenos Aires.<\/strong><\/p>\n<p>El primer lugar al que debemos ir es al <strong>Estadio de Argentinos Juniors<\/strong>, ubicado en la calle <strong>Gavil\u00e1n 2151<\/strong>, dado que <strong>aqu\u00ed fue donde jug\u00f3 como profesional por primera vez en el a\u00f1o 1976.<\/strong> El estadio cuenta con su museo propio, donde encontrar\u00e1s los reconocimientos y trofeos que consigui\u00f3 Maradona en su paso por este Club.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13894 alignright\" src=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona3.jpg?resize=300%2C200&#038;ssl=1\" alt=\"Tour Diego Armando Maradona\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona3.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona3.jpg?resize=272%2C182&amp;ssl=1 272w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Luego de su muerte, <strong>muchos fan\u00e1ticos han asistido al estadio para dejarle una ofrenda, por lo que el club de Argentinos Juniors decidi\u00f3 abrir un Santuario para Maradona<\/strong>, con un mural del Diego enorme, adem\u00e1s de colocar bancos cual si fuera una iglesia Maradoniana. <strong>Una escultura de bronce se encuentra a unos metros del estadio, en la calle Gavil\u00e1n y \u00c1lvarez Jonte<\/strong>, que es un regalo del barrio para honrar a Maradona. Tambi\u00e9n, encontrar\u00e1s <strong>las paredes del estadio con murales que lo representan con sus padres, Do\u00f1a Tota y Don Diego, con la pelota y con la camiseta de Argentina, elevando la Copa del Mundial de M\u00e9xico 86\u2019.<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13896 alignleft\" src=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona5.jpg?resize=300%2C200&#038;ssl=1\" alt=\"Tour Diego Armando Maradona\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona5.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona5.jpg?resize=272%2C182&amp;ssl=1 272w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Despu\u00e9s de la visita al Santuario, nos vamos a trasladar<strong> hacia la calle Lascano 2257<\/strong>, para visitar <strong>la Casa Museo de Diego Maradona<\/strong>,\u00a0actualmente,<em><strong> &#8220;La<\/strong><\/em><i style=\"font-weight: bold;\">\u00a0Casa de D10S&#8221;<\/i><b>.<\/b> Aqu\u00ed fue <strong>donde vivi\u00f3 Diego y su familia entre los a\u00f1os 1978 y 1980.<\/strong> Se trata de la casa, devenida en museo, a escasos metros del estadio de Argentinos Juniors. Luego del debut de Maradona en 1976, los directivos de Argentinos Juniors le compraron la casa. Actualmente, <strong>se conserva la decoraci\u00f3n y muebles originales, junto con el piano que Maradona sol\u00eda tocar.<\/strong> Se<strong> realizan visitas<\/strong>, por lo que <a href=\"http:\/\/www.lacasaded10s.com\/\" target=\"_blank\" rel=\"noopener\">te dejamos aqu\u00ed el sitio web para que puedas reservar y entrar al mundo de Maradona<\/a>, traslad\u00e1ndote a una \u00e9poca de hace 40 a\u00f1os atr\u00e1s.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13895 alignright\" src=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona4.jpg?resize=300%2C200&#038;ssl=1\" alt=\"Tour Diego Armando Maradona\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona4.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona4.jpg?resize=272%2C182&amp;ssl=1 272w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ahora es el momento en que nos movemos de barrio, para irnos <strong>hasta Retiro, espec\u00edficamente a la calle San Mart\u00edn 1035, para visitar la Bas\u00edlica del Sant\u00edsimo Sacramento.<\/strong> Te preguntar\u00e1s por qu\u00e9 vamos a una iglesia y la respuesta es simple,<strong> aqu\u00ed es donde Maradona contrajo matrimonio con su primera esposa, la reconocida Claudia Villafa\u00f1e.<\/strong> La misma, es <strong>madre de las mundialmente conocidas hijas de Maradona: Dalma y Giannina.<\/strong> Al margen de ser el sitio donde el Diego se cas\u00f3, se trata de una iglesia que <strong>se construy\u00f3 en 1914, considerada la m\u00e1s antigua y lujosa de la ciudad. Con un estilo ecl\u00e9ctico<\/strong>, merece que le dediques una visita!<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-13898 size-full alignleft\" src=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona6-1.jpg?resize=300%2C200&#038;ssl=1\" alt=\"Boca Juniors\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona6-1.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona6-1.jpg?resize=272%2C182&amp;ssl=1 272w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Es sabido que <strong>el gran amor de Diego Maradona, es el Club Boca Juniors.<\/strong> Por esto mismo, <strong>es imposible no incluir al Estadio de Boca Juniors en nuestro recorrido.<\/strong> Ubicado <strong>en el barrio de la Boca<\/strong> y mundialmente conocido como <em>\u201cLa Bombonera\u201d<\/em>, fue el e<strong>stadio que pudo tener a Maradona jugando entre los a\u00f1os 1981 y 1982, para regresar en 1995 y quedarse por dos a\u00f1os m\u00e1s.<\/strong> En <strong>1997, Maradona decidi\u00f3 retirarse del f\u00fatbol con la camiseta que siempre am\u00f3, la azul y amarilla.<\/strong><\/p>\n<p>Para llegar aqu\u00ed, debes acercarte a la <strong>calle Brandsen 805<\/strong>, no est\u00e1 tan lejos del barrio de Retiro si primero vas a la Bas\u00edlica que mencionamos antes. En este caso, <strong>la Bombonera es un museo entero, donde miles de turistas se acercan a recorrerla, visitando los vestidores, las tribunas y hasta el palco privado que utilizaba Maradona para ver a su gran amor.<\/strong><\/p>\n<p>Aqu\u00ed, tambi\u00e9n, vas a encontrar el <strong>Museo de la Pasi\u00f3n Boquense<\/strong>, donde podr\u00e1s recorrer <strong>100 a\u00f1os de la historia del Club Boca Juniors<\/strong>, la evoluci\u00f3n de su camiseta y todos los jugadores que fueron parte de su historia.<\/p>\n<p>Para <a href=\"https:\/\/www.buenosairesfreewalks.com\/spanish\/barrio\/la-boca\/que-hacer-en-la-boca\/\" target=\"_blank\" rel=\"noopener\">saber todo lo que puedes hacer en el barrio de la Boca, te dejamos esta nota aqu\u00ed.<\/a><\/p>\n<p>Tambi\u00e9n, aprovechamos para invitarte a que <a href=\"https:\/\/www.buenosairesfreewalks.com\/spanish\/free-tour-la-boca\/\" target=\"_blank\" rel=\"noopener\">te unas aqu\u00ed a nuestro Free Tour La Boca<\/a> y te enteres de la historia de este t\u00edpico barrio porte\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<h4>BONUS EXTRA<\/h4>\n<p>Claramente, <strong>La Boca y Paternal, son los barrios que m\u00e1s historia tienen sobre Diego Maradona.<\/strong> Por esto mismo, tienes que abrir bien los ojos para poder observar todos los murales que colorean las paredes de estas zonas.<\/p>\n<p>Aqu\u00ed queremos dejarte algunos destacados para que no te los pierdas:<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13899 alignright\" src=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona.jpg?resize=300%2C200&#038;ssl=1\" alt=\"Murales Maradona\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/maradona.jpg?resize=272%2C182&amp;ssl=1 272w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<ul>\n<li>La esquina de las calles Brandsen y Juan de Dios Filiberto, La Boca: Mural inmenso donde ver\u00e1s a Maradona levantando la copa del Mundo, jugando con la camiseta de Boca Juniors, con la de Argentina y gritando un gol. Exactamente, es en la esquina frente al Estadio de La Bombonera.<\/li>\n<li>Entre las calles Irala y Arist\u00f3bulo del Valle, La Boca: El inolvidable gol del mundial de 1986, seguido a la palabra \u201cD10S\u201d.<\/li>\n<li>Arist\u00f3bulo del Valle 50, La Boca: Maradona vestido de santo.<\/li>\n<li>Boyac\u00e1 2145, Paternal: En las paredes externas de Argentinos Juniors, se trata de uno de los murales m\u00e1s visitados por los fan\u00e1ticos que admiran al jugador.<\/li>\n<li>La esquina de las calles San Blas y Boyac\u00e1, Paternal: \u201cOrgullo de un barrio\u201d es el t\u00edtulo de esta magn\u00edfica obra, donde Diego tiene la camiseta de Argentinos Juniors.<\/li>\n<li>Entre las calles Linneo y \u00c1lvarez Jonte, Paternal: Se trata de uno de los murales m\u00e1s conocidos y m\u00e1s altos de este barrio, ubicado en la Casa Museo de Maradona. Con once metros de altura, se puede ver desde la calle, pintado en la terraza del edificio.<\/li>\n<li>La esquina de Miguel \u00c1ngel y Av. San Mart\u00edn: con el t\u00edtulo de \u201cTierra de Dios\u201d, se puede ver a Maradona con la camiseta de Argentinos Juniors.<\/li>\n<\/ul>\n<p><strong>Diego Armando Maradona fue m\u00e1s que un jugador de f\u00fatbol.<\/strong> Para los argentinos<strong> se trata de una leyenda urbana y cultural, un personaje que es m\u00e1s un s\u00edmbolo que no conoce fronteras<\/strong>, ya que nos hizo conocidos en el mundo entero. El \u00eddolo de todos, homenajeado alrededor de la ciudad, porque en cada rinc\u00f3n, el n\u00famero 10 es igual al Diego, es igual a D10S.<\/p>\n<p>&nbsp;<\/p>\n<h4>Mapa de Atracciones<\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/u\/1\/embed?mid=1h8w2S9s_WXgNkPF9GitBqkNQLqKn2-ku&amp;ehbc=2E312F\" width=\"640\" height=\"480\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tour Diego Armando Maradona, un recorrido por los barrios que homenajean al \u00eddolo nacional, reconocido por el mundo entero! Hace un a\u00f1o que El Diego, o D10S, como se lo conoce popularmente, abandon\u00f3 la vida terrenal, para sorpresa del mundo. S\u00ed, es una de las personalidades m\u00e1s fuertes y el mayor \u00eddolo que poseen los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[572],"tags":[],"class_list":["post-13893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-ver"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour Diego Armando Maradona | Buenos Aires Free Walks<\/title>\n<meta name=\"description\" content=\"Tour Diego Armando Maradona, un recorrido por los barrios en donde empez\u00f3 su historia como \u00eddolo mundial del f\u00fatbol. Enterate de todo aqu\u00ed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour Diego Armando Maradona | Buenos Aires Free Walks\" \/>\n<meta property=\"og:description\" content=\"Tour Diego Armando Maradona, un recorrido por los barrios en donde empez\u00f3 su historia como \u00eddolo mundial del f\u00fatbol. Enterate de todo aqu\u00ed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/\" \/>\n<meta property=\"og:site_name\" content=\"Buenos Aires Free Walks\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-31T17:23:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-31T17:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/tour-maradona_portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Free Walks\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Free Walks\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour Diego Armando Maradona | Buenos Aires Free Walks","description":"Tour Diego Armando Maradona, un recorrido por los barrios en donde empez\u00f3 su historia como \u00eddolo mundial del f\u00fatbol. Enterate de todo aqu\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/","og_locale":"es_ES","og_type":"article","og_title":"Tour Diego Armando Maradona | Buenos Aires Free Walks","og_description":"Tour Diego Armando Maradona, un recorrido por los barrios en donde empez\u00f3 su historia como \u00eddolo mundial del f\u00fatbol. Enterate de todo aqu\u00ed!","og_url":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/","og_site_name":"Buenos Aires Free Walks","article_published_time":"2022-01-31T17:23:36+00:00","article_modified_time":"2022-01-31T17:49:39+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/tour-maradona_portada.jpg","type":"image\/jpeg"}],"author":"Free Walks","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Free Walks","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/#article","isPartOf":{"@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/"},"author":{"name":"Free Walks","@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/#\/schema\/person\/dce399cd8b4deeac2634e082f915794c"},"headline":"Tour Diego Armando Maradona","datePublished":"2022-01-31T17:23:36+00:00","dateModified":"2022-01-31T17:49:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/"},"wordCount":1120,"commentCount":2,"image":{"@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/tour-maradona_portada.jpg?fit=1200%2C600&ssl=1","articleSection":["Que ver"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/","url":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/","name":"Tour Diego Armando Maradona | Buenos Aires Free Walks","isPartOf":{"@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/#primaryimage"},"image":{"@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/tour-maradona_portada.jpg?fit=1200%2C600&ssl=1","datePublished":"2022-01-31T17:23:36+00:00","dateModified":"2022-01-31T17:49:39+00:00","author":{"@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/#\/schema\/person\/dce399cd8b4deeac2634e082f915794c"},"description":"Tour Diego Armando Maradona, un recorrido por los barrios en donde empez\u00f3 su historia como \u00eddolo mundial del f\u00fatbol. Enterate de todo aqu\u00ed!","breadcrumb":{"@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/#primaryimage","url":"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/tour-maradona_portada.jpg?fit=1200%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/tour-maradona_portada.jpg?fit=1200%2C600&ssl=1","width":1200,"height":600,"caption":"Tour Diego Armando Maradona"},{"@type":"BreadcrumbList","@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/que-ver\/tour-diego-armando-maradona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buenosairesfreewalks.com\/spanish\/"},{"@type":"ListItem","position":2,"name":"Tour Diego Armando Maradona"}]},{"@type":"WebSite","@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/#website","url":"https:\/\/www.buenosairesfreewalks.com\/spanish\/","name":"Buenos Aires Free Walks","description":"Los Mejores Tours Gratis en Buenos Aires","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buenosairesfreewalks.com\/spanish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/www.buenosairesfreewalks.com\/spanish\/#\/schema\/person\/dce399cd8b4deeac2634e082f915794c","name":"Free Walks","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/cd67a9467fd175bde4cdfe7ebd3199788e97fb329e3ea88fd8755654e324b841?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd67a9467fd175bde4cdfe7ebd3199788e97fb329e3ea88fd8755654e324b841?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd67a9467fd175bde4cdfe7ebd3199788e97fb329e3ea88fd8755654e324b841?s=96&d=mm&r=g","caption":"Free Walks"},"url":"https:\/\/www.buenosairesfreewalks.com\/spanish\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.buenosairesfreewalks.com\/spanish\/wp-content\/uploads\/2022\/01\/tour-maradona_portada.jpg?fit=1200%2C600&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/posts\/13893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/comments?post=13893"}],"version-history":[{"count":2,"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/posts\/13893\/revisions"}],"predecessor-version":[{"id":13902,"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/posts\/13893\/revisions\/13902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/media\/13900"}],"wp:attachment":[{"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/media?parent=13893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/categories?post=13893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buenosairesfreewalks.com\/spanish\/wp-json\/wp\/v2\/tags?post=13893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}